{"id":220018,"date":"2021-10-01T13:44:32","date_gmt":"2021-10-01T11:44:32","guid":{"rendered":"https:\/\/highxtar.com\/?p=220018"},"modified":"2021-10-01T13:46:54","modified_gmt":"2021-10-01T11:46:54","slug":"coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection","status":"publish","type":"post","link":"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/","title":{"rendered":"Coperni takes Ibiza as the inspiration for its SS22 collection"},"content":{"rendered":"<p><strong>The duo of designers who make up one of the fashion brands of the moment, S\u00e9bastien Meyer and Arnaud Vaillant de <a href=\"https:\/\/highxtar.com\/coperni-f21-rtw-or-how-to-turn-a-fashion-show-into-a-drive-in-runway\/?lang=en\" target=\"_blank\" rel=\"noopener\">Coperni<\/a>, have just presented their latest Spring\/Summer collection, but unlike on other occasions, the couple did not want to place this collection in the year 2022, but preferred to call it 2023 and thus place it in another space.<\/strong><strong><img decoding=\"async\" class=\"alignnone size-full wp-image-220012\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-gigi-hadid-coperni-pfw-ss23-1.jpg\" alt=\"\" width=\"959\" height=\"639\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-gigi-hadid-coperni-pfw-ss23-1.jpg 959w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-gigi-hadid-coperni-pfw-ss23-1-300x200.jpg 300w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-gigi-hadid-coperni-pfw-ss23-1-768x512.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-gigi-hadid-coperni-pfw-ss23-1-508x338.jpg 508w\" sizes=\"(max-width: 959px) 100vw, 959px\" \/><\/strong><\/p>\n<p>Held in front of a small number of guests, with a cast of &#8220;top models&#8221; worthy of a French catwalk and led by <strong>Gigi Hadid, Adut Aketch, Mica Arga\u00f1araz or Paloma Elsesser<\/strong>, they all began to glide on the sand catwalk, specially designed for the occasion, and among the <strong>70,000 hemp stalks and on the sand catwalk<\/strong>, with the latest creations of the designers.<\/p>\n<p>This collection to which we refer, <strong>took as a great source of inspiration the island of Ibiza,<\/strong> which for the couple was a clear aspiring place for their customers to wear the pieces or accessories. Among the garments in this line, we can see how the <strong>French brand continues to preserve its clear aesthetic that characterises<\/strong> it so much, but <strong>we can also see how on this occasion it takes a step forward, leaving its comfort zone and introducing new floral and psychedelic prints and others in &#8220;patchwork&#8221; format.<\/strong>\u00a0 Finally, we have to highlight <strong>its blazers cut vertically above the armpit and suspended on the body by a halter neck with acetate chain and its dresses with rings in the form of straps and in the chest area.<\/strong><\/p>\n<div id='gallery-1' class='gallery galleryid-220018 gallery-columns-2 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-1-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-1.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-1-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-1-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-1-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-1-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-1-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-1-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-1-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-2-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-2.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-2-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-2-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-2-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-2-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-2-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-2-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-2-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-3-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-3.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-3-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-3-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-3-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-3-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-3-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-3-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-3-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-4-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-4.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-4.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-4-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-4-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-4-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-4-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-4-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-4-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-4-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-5-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-5.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-5.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-5-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-5-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-5-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-5-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-5-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-5-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-5-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-6-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-6.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-6.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-6-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-6-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-6-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-6-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-6-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-6-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-6-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-7-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-7.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-7.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-7-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-7-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-7-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-7-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-7-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-7-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-7-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-8-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-8.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-8.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-8-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-8-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-8-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-8-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-8-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-8-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-8-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-9-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-9.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-9.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-9-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-9-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-9-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-9-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-9-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-9-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-9-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-10-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-10.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-10.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-10-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-10-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-10-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-10-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-10-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-10-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-10-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-11-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-11.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-11.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-11-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-11-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-11-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-11-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-11-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-11-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-11-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-12-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-12.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-12.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-12-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-12-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-12-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-12-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-12-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-12-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-12-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-13-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-13.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-13.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-13-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-13-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-13-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-13-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-13-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-13-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-13-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-14-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-14.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-14.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-14-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-14-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-14-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-14-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-14-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-14-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-14-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-15-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-15.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-15.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-15-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-15-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-15-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-15-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-15-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-15-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-15-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-16-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-16.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-16.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-16-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-16-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-16-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-16-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-16-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-16-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-16-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-17-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-17.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-17.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-17-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-17-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-17-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-17-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-17-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-17-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-17-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-18-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-18.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-18.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-18-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-18-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-18-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-18-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-18-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-18-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-18-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-19-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-19.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-19.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-19-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-19-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-19-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-19-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-19-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-19-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-19-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-20-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-20.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-20.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-20-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-20-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-20-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-20-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-20-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-20-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-20-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-21-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-21.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-21.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-21-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-21-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-21-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-21-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-21-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-21-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-21-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-22-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-22.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-22.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-22-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-22-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-22-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-22-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-22-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-22-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-22-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-23-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-23.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-23.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-23-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-23-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-23-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-23-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-23-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-23-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-23-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-24-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-24.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-24.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-24-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-24-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-24-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-24-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-24-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-24-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-24-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-25-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-25.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-25.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-25-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-25-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-25-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-25-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-25-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-25-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-25-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-26-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-26.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-26.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-26-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-26-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-26-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-26-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-26-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-26-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-26-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-27-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-27.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-27.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-27-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-27-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-27-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-27-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-27-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-27-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-27-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-28-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-28.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-28.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-28-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-28-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-28-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-28-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-28-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-28-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-28-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-29-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-29.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-29.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-29-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-29-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-29-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-29-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-29-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-29-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-29-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-30-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-30.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-30.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-30-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-30-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-30-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-30-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-30-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-30-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-30-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-31-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-31.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-31.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-31-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-31-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-31-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-31-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-31-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-31-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-31-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-32-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-32.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-32.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-32-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-32-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-32-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-32-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-32-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-32-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-32-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/highxtar-coperni-ss22-33-2\/'><img decoding=\"async\" width=\"2240\" height=\"3360\" src=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-33.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-33.jpg 2240w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-33-200x300.jpg 200w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-33-683x1024.jpg 683w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-33-768x1152.jpg 768w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-33-1024x1536.jpg 1024w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-33-1365x2048.jpg 1365w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-33-973x1460.jpg 973w, https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/highxtar-coperni-ss22-33-508x762.jpg 508w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>What do you think of this latest <strong>Spring\/Summer 23 collection<\/strong> by <a href=\"https:\/\/www.instagram.com\/coperni\/?hl=es\" target=\"_blank\" rel=\"noopener\"><strong>Coperni<\/strong><\/a>? We can&#8217;t wait for next summer to arrive so we can wear any of their garments. <strong>Check out the gallery to see the collection in its entirety.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e9bastien Meyer and Arnaud Vaillant have just presented their upcoming Spring\/Summer collection for the firm they run, Coperni.<\/p>\n","protected":false},"author":28,"featured_media":220008,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[603],"tags":[2227,922],"class_list":["post-220018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fashion-en","tag-gabriel-cordoba-en","tag-pfw-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin  - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coperni takes Ibiza as the inspiration for its SS22 collection - HIGHXTAR.<\/title>\n<meta name=\"description\" content=\"S\u00e9bastien Meyer and Arnaud Vaillant have just presented their upcoming Spring\/Summer collection for the firm they run, Coperni.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coperni takes Ibiza as the inspiration for its SS22 collection\" \/>\n<meta property=\"og:description\" content=\"S\u00e9bastien Meyer and Arnaud Vaillant have just presented their upcoming Spring\/Summer collection for the firm they run, Coperni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/\" \/>\n<meta property=\"og:site_name\" content=\"HIGHXTAR.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/highxtar\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-01T11:44:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-01T11:46:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/Thumb-H-gigi-hadid-coperni-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriel C\u00f3rdoba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@highxtar_\" \/>\n<meta name=\"twitter:site\" content=\"@highxtar_\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel C\u00f3rdoba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/highxtar.com\\\/en\\\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/highxtar.com\\\/en\\\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\\\/\"},\"author\":{\"name\":\"Gabriel C\u00f3rdoba\",\"@id\":\"https:\\\/\\\/highxtar.com\\\/#\\\/schema\\\/person\\\/d1c739ec02ef7608ab9e0acf22647c4d\"},\"headline\":\"Coperni takes Ibiza as the inspiration for its SS22 collection\",\"datePublished\":\"2021-10-01T11:44:32+00:00\",\"dateModified\":\"2021-10-01T11:46:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/highxtar.com\\\/en\\\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\\\/\"},\"wordCount\":307,\"publisher\":{\"@id\":\"https:\\\/\\\/highxtar.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/highxtar.com\\\/en\\\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/highxtar.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Thumb-H-gigi-hadid-coperni-1.jpg\",\"keywords\":[\"Gabriel C\u00f3rdoba\",\"PFW\"],\"articleSection\":[\"Fashion\"],\"inLanguage\":\"en-US\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/highxtar.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/highxtar.com\\\/en\\\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\\\/\",\"url\":\"https:\\\/\\\/highxtar.com\\\/en\\\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\\\/\",\"name\":\"Coperni takes Ibiza as the inspiration for its SS22 collection - HIGHXTAR.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/highxtar.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/highxtar.com\\\/en\\\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/highxtar.com\\\/en\\\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/highxtar.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Thumb-H-gigi-hadid-coperni-1.jpg\",\"datePublished\":\"2021-10-01T11:44:32+00:00\",\"dateModified\":\"2021-10-01T11:46:54+00:00\",\"description\":\"S\u00e9bastien Meyer and Arnaud Vaillant have just presented their upcoming Spring\\\/Summer collection for the firm they run, Coperni.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/highxtar.com\\\/en\\\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/highxtar.com\\\/en\\\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/highxtar.com\\\/en\\\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\\\/#primaryimage\",\"url\":\"https:\\\/\\\/highxtar.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Thumb-H-gigi-hadid-coperni-1.jpg\",\"contentUrl\":\"https:\\\/\\\/highxtar.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Thumb-H-gigi-hadid-coperni-1.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/highxtar.com\\\/en\\\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/highxtar.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coperni takes Ibiza as the inspiration for its SS22 collection\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/highxtar.com\\\/#website\",\"url\":\"https:\\\/\\\/highxtar.com\\\/\",\"name\":\"HIGHXTAR.\",\"description\":\"HIGHXTAR. es la voz latina de la moda y el streetwear. Devotos de las cosas que hacen la vida urbana excitante: Moda, M\u00fasica, Lifestyle, Arte &amp; Dise\u00f1o.\",\"publisher\":{\"@id\":\"https:\\\/\\\/highxtar.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/highxtar.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/highxtar.com\\\/#organization\",\"name\":\"HIGHXTAR.\",\"url\":\"https:\\\/\\\/highxtar.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/highxtar.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/highxtar.com\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/HIGHXTAR_com_Favicon_2019.jpg\",\"contentUrl\":\"https:\\\/\\\/highxtar.com\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/HIGHXTAR_com_Favicon_2019.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"HIGHXTAR.\"},\"image\":{\"@id\":\"https:\\\/\\\/highxtar.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/highxtar\",\"https:\\\/\\\/x.com\\\/highxtar_\",\"https:\\\/\\\/www.instagram.com\\\/highxtar\",\"https:\\\/\\\/www.tiktok.com\\\/@highxtar\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/highxtarofficial\",\"https:\\\/\\\/open.spotify.com\\\/user\\\/highxtar\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/highxtar.com\\\/#\\\/schema\\\/person\\\/d1c739ec02ef7608ab9e0acf22647c4d\",\"name\":\"Gabriel C\u00f3rdoba\",\"description\":\"Colaborador de HIGHXTAR. con base en Madrid. HIGHXTAR. contributor based in\u00a0Madrid.\",\"url\":\"https:\\\/\\\/highxtar.com\\\/en\\\/author\\\/gabicoac\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coperni takes Ibiza as the inspiration for its SS22 collection - HIGHXTAR.","description":"S\u00e9bastien Meyer and Arnaud Vaillant have just presented their upcoming Spring\/Summer collection for the firm they run, Coperni.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/","og_locale":"en_US","og_type":"article","og_title":"Coperni takes Ibiza as the inspiration for its SS22 collection","og_description":"S\u00e9bastien Meyer and Arnaud Vaillant have just presented their upcoming Spring\/Summer collection for the firm they run, Coperni.","og_url":"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/","og_site_name":"HIGHXTAR.","article_publisher":"https:\/\/www.facebook.com\/highxtar","article_published_time":"2021-10-01T11:44:32+00:00","article_modified_time":"2021-10-01T11:46:54+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/Thumb-H-gigi-hadid-coperni-1.jpg","type":"image\/jpeg"}],"author":"Gabriel C\u00f3rdoba","twitter_card":"summary_large_image","twitter_creator":"@highxtar_","twitter_site":"@highxtar_","twitter_misc":{"Written by":"Gabriel C\u00f3rdoba","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/#article","isPartOf":{"@id":"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/"},"author":{"name":"Gabriel C\u00f3rdoba","@id":"https:\/\/highxtar.com\/#\/schema\/person\/d1c739ec02ef7608ab9e0acf22647c4d"},"headline":"Coperni takes Ibiza as the inspiration for its SS22 collection","datePublished":"2021-10-01T11:44:32+00:00","dateModified":"2021-10-01T11:46:54+00:00","mainEntityOfPage":{"@id":"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/"},"wordCount":307,"publisher":{"@id":"https:\/\/highxtar.com\/#organization"},"image":{"@id":"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/#primaryimage"},"thumbnailUrl":"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/Thumb-H-gigi-hadid-coperni-1.jpg","keywords":["Gabriel C\u00f3rdoba","PFW"],"articleSection":["Fashion"],"inLanguage":"en-US","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/highxtar.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/","url":"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/","name":"Coperni takes Ibiza as the inspiration for its SS22 collection - HIGHXTAR.","isPartOf":{"@id":"https:\/\/highxtar.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/#primaryimage"},"image":{"@id":"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/#primaryimage"},"thumbnailUrl":"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/Thumb-H-gigi-hadid-coperni-1.jpg","datePublished":"2021-10-01T11:44:32+00:00","dateModified":"2021-10-01T11:46:54+00:00","description":"S\u00e9bastien Meyer and Arnaud Vaillant have just presented their upcoming Spring\/Summer collection for the firm they run, Coperni.","breadcrumb":{"@id":"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/#primaryimage","url":"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/Thumb-H-gigi-hadid-coperni-1.jpg","contentUrl":"https:\/\/highxtar.com\/wp-content\/uploads\/2021\/10\/Thumb-H-gigi-hadid-coperni-1.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/highxtar.com\/en\/coperni-takes-ibiza-as-the-inspiration-for-its-ss22-collection\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/highxtar.com\/en\/"},{"@type":"ListItem","position":2,"name":"Coperni takes Ibiza as the inspiration for its SS22 collection"}]},{"@type":"WebSite","@id":"https:\/\/highxtar.com\/#website","url":"https:\/\/highxtar.com\/","name":"HIGHXTAR.","description":"HIGHXTAR. es la voz latina de la moda y el streetwear. Devotos de las cosas que hacen la vida urbana excitante: Moda, M\u00fasica, Lifestyle, Arte &amp; Dise\u00f1o.","publisher":{"@id":"https:\/\/highxtar.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/highxtar.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/highxtar.com\/#organization","name":"HIGHXTAR.","url":"https:\/\/highxtar.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/highxtar.com\/#\/schema\/logo\/image\/","url":"https:\/\/highxtar.com\/wp-content\/uploads\/2016\/03\/HIGHXTAR_com_Favicon_2019.jpg","contentUrl":"https:\/\/highxtar.com\/wp-content\/uploads\/2016\/03\/HIGHXTAR_com_Favicon_2019.jpg","width":1200,"height":1200,"caption":"HIGHXTAR."},"image":{"@id":"https:\/\/highxtar.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/highxtar","https:\/\/x.com\/highxtar_","https:\/\/www.instagram.com\/highxtar","https:\/\/www.tiktok.com\/@highxtar","https:\/\/www.youtube.com\/c\/highxtarofficial","https:\/\/open.spotify.com\/user\/highxtar"]},{"@type":"Person","@id":"https:\/\/highxtar.com\/#\/schema\/person\/d1c739ec02ef7608ab9e0acf22647c4d","name":"Gabriel C\u00f3rdoba","description":"Colaborador de HIGHXTAR. con base en Madrid. HIGHXTAR. contributor based in\u00a0Madrid.","url":"https:\/\/highxtar.com\/en\/author\/gabicoac\/"}]}},"_links":{"self":[{"href":"https:\/\/highxtar.com\/en\/wp-json\/wp\/v2\/posts\/220018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/highxtar.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/highxtar.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/highxtar.com\/en\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/highxtar.com\/en\/wp-json\/wp\/v2\/comments?post=220018"}],"version-history":[{"count":3,"href":"https:\/\/highxtar.com\/en\/wp-json\/wp\/v2\/posts\/220018\/revisions"}],"predecessor-version":[{"id":220027,"href":"https:\/\/highxtar.com\/en\/wp-json\/wp\/v2\/posts\/220018\/revisions\/220027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/highxtar.com\/en\/wp-json\/wp\/v2\/media\/220008"}],"wp:attachment":[{"href":"https:\/\/highxtar.com\/en\/wp-json\/wp\/v2\/media?parent=220018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/highxtar.com\/en\/wp-json\/wp\/v2\/categories?post=220018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/highxtar.com\/en\/wp-json\/wp\/v2\/tags?post=220018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}